{"id":3001,"date":"2021-12-13T01:53:10","date_gmt":"2021-12-13T01:53:10","guid":{"rendered":"https:\/\/www.raxdoor.com\/?p=3001"},"modified":"2024-04-04T13:27:58","modified_gmt":"2024-04-04T13:27:58","slug":"garage-door-suppliers-in-canada","status":"publish","type":"post","link":"https:\/\/www.raxdoor.com\/pt\/garage-door-suppliers-in-canada\/","title":{"rendered":"Os 10 principais fornecedores e atacadistas de portas de garagem no Canad\u00e1"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-top vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"1400\" height=\"700\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2022\/01\/Garage-Door-Wholesalers-in-Canada.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"Atacadistas de portas de garagem no Canad\u00e1\" title=\"Atacadistas de portas de garagem no Canad\u00e1\" srcset=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2022\/01\/Garage-Door-Wholesalers-in-Canada.jpg 1400w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2022\/01\/Garage-Door-Wholesalers-in-Canada-300x150.jpg 300w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2022\/01\/Garage-Door-Wholesalers-in-Canada-1024x512.jpg 1024w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2022\/01\/Garage-Door-Wholesalers-in-Canada-768x384.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\"  data-dt-location=\"https:\/\/www.raxdoor.com\/pt\/garage-door-suppliers-in-austria\/garage-door-wholesalers-in-canada\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607261710231 vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Voc\u00ea quer saber quem est\u00e1 liderando a ind\u00fastria de portas de garagem no Canad\u00e1? Neste artigo, listamos os principais fornecedores e atacadistas de portas de garagem para aplica\u00e7\u00f5es residenciais, comerciais e industriais.<\/p>\n<h2><span id=\"Garage_Door_Manufacturers_Suppliers_List_in_the_USA\">Melhores empresas de portas de garagem em <span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"11\">Canad\u00e1<\/span><\/span><\/h2>\n<h3>Uma porta de garagem<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter wp-image-4537\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/1.-Canadian-Wholesale-Garage-Door-Supplier-A-One-Garage-Doors.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - A One Garage Doors\" width=\"300\" height=\"170\" \/>Fonte: aonegaragedoors.com<\/p>\n<p>A A-ONE Garage Door projeta e fabrica produtos de portas de garagem isoladas de alta qualidade para os mercados canadenses a partir de nossas f\u00e1bricas em Ont\u00e1rio.<\/p>\n<p>Como uma marca l\u00edder no setor de portas de garagem, a A-ONE est\u00e1 comprometida em oferecer uma ampla variedade de designs diferenciados e ferramentas de sele\u00e7\u00e3o \u00fateis para clientes em todo o Canad\u00e1.<\/p>\n<p>Nossa gama completa de produtos tamb\u00e9m abrange abridores de portas de garagem el\u00e9tricos e muitos outros acess\u00f3rios para combinar com sua porta de garagem. Tamb\u00e9m oferecemos servi\u00e7o completo de instala\u00e7\u00e3o e reparo.<\/p>\n<p>Sede: 45 West Wilmot Street, Unidade B10-12, Richmond Hill, Ont\u00e1rio, L4B 2P2<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-8430\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1637545308133\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-8430 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d333f33850-93054553\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d333f33850-93054553\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d333f33850-93054553\" data-class=\"content-6a57d333f33850-93054553\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-1304\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-1304 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Garaga Inc.<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-medium wp-image-4538 aligncenter\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/2.-Canadian-Wholesale-Garage-Door-Supplier-Garaga-Inc.-300x146.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - Garaga Inc.\" width=\"300\" height=\"146\" srcset=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/2.-Canadian-Wholesale-Garage-Door-Supplier-Garaga-Inc.-300x146.png 300w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/2.-Canadian-Wholesale-Garage-Door-Supplier-Garaga-Inc..png 515w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Fonte: garaga.com<\/p>\n<p>Fundada em 1983, a Garaga \u00e9 uma das principais fabricantes de portas de garagem e portas basculantes no Canad\u00e1. Uma empresa familiar, ela projeta e fabrica portas de garagem superiores e os sistemas de ferragens relacionados para os mercados residencial, comercial, agr\u00edcola e industrial.<\/p>\n<p>Eles t\u00eam 3 plantas de produ\u00e7\u00e3o: St\u2011Georges (148.000 p\u00e9s quadrados), Barrie (115.000 p\u00e9s quadrados) e Ponca City, OK (180.000 p\u00e9s quadrados). Eles venderam e instalaram mais de 3,6 milh\u00f5es de portas de garagem desde 1983.<\/p>\n<p>Principais produtos:<\/p>\n<ul>\n<li>Portas de garagem tradicionais<\/li>\n<li>Portas de garagem contempor\u00e2neas<\/li>\n<li>Portas de garagem Carriage House<\/li>\n<li>Abridores de portas de garagem<\/li>\n<\/ul>\n<p>Sede: 8500 25th Avenue, St-Georges (QC), Canad\u00e1<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-1260\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-1260 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d334018a37-33760209\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d334018a37-33760209\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d334018a37-33760209\" data-class=\"content-6a57d334018a37-33760209\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-2587\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-2587 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o2\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>PORTAS JPR<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter wp-image-4539\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/3.-Canadian-Wholesale-Garage-Door-Supplier-J.P.R.-DOORS.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - JPR DOORS\" width=\"300\" height=\"134\" \/>Fonte: jpr.ca<\/p>\n<p>A JPR \u00e9 a principal refer\u00eancia em fabrica\u00e7\u00e3o, distribui\u00e7\u00e3o, instala\u00e7\u00e3o ou reparo de portas de garagem. Nossa abordagem global nos permite estar a servi\u00e7o de todos, respondendo a desafios industriais ou residenciais. Temos a expertise para intervir em todas as situa\u00e7\u00f5es e novas solu\u00e7\u00f5es est\u00e3o dispon\u00edveis para ajudar voc\u00ea a personalizar sua porta. Nossa abordagem beneficiar\u00e1 suas opera\u00e7\u00f5es, fornecer\u00e1 uma apar\u00eancia exclusiva e embelezar\u00e1 seu ambiente.<\/p>\n<p>Principais produtos:<\/p>\n<ul>\n<li>Port\u00f5es de garagem residenciais<\/li>\n<li>Portas de garagem comerciais<\/li>\n<li>Abridor de porta de garagem<\/li>\n<\/ul>\n<p>Sede: 4800 highway Laval (440) West, Laval, Quebec H7T 2Z8 CANAD\u00c1<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-6584\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-6584 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d334036518-21193737\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d334036518-21193737\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d334036518-21193737\" data-class=\"content-6a57d334036518-21193737\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-7428\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-7428 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o3\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o3\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o3\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o3\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>PORTA DO NORTE DO CANAD\u00c1, LTDA<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter wp-image-4540\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/4.-Canadian-Wholesale-Garage-Door-Supplier-NORTHWEST-DOOR-CANADA-LTD.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - NORTHWEST DOOR CANADA, LTD\" width=\"300\" height=\"67\" \/>Fonte: nwdca.ca<\/p>\n<p>A Northwest Door Canada \u00e9 uma atacadista de portas de garagem residenciais e comerciais e abridores. Nosso pr\u00e9dio de 50 mil p\u00e9s quadrados est\u00e1 localizado em Surrey, BC, e apresenta um showroom elaborado exibindo uma variedade de belas portas de garagem da Northwest Door. Tamb\u00e9m temos filiais em Kelowna, BC (5.000 p\u00e9s quadrados) e Calgary, AB (19.000 p\u00e9s quadrados).<\/p>\n<p>A Northwest Door Canada \u00e9 uma empresa familiar com uma for\u00e7a de trabalho altamente dedicada e bem treinada. Temos orgulho em fornecer uma das mais amplas gamas de portas de garagem residenciais e comerciais de alta qualidade do setor.<\/p>\n<p>Sede: 4155 75 Ave SE, Calgary, AB T2C 2K8, Canad\u00e1<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-9046\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-9046 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d334053097-63952081\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d334053097-63952081\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d334053097-63952081\" data-class=\"content-6a57d334053097-63952081\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-694\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-694 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o4\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o4\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o4\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o4\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Portas Garex Enr.<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-medium wp-image-4541 aligncenter\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/5.-Canadian-Wholesale-Garage-Door-Supplier-Garex-Doors-Enr.-300x99.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - Garex Doors Enr.\" width=\"300\" height=\"99\" srcset=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/5.-Canadian-Wholesale-Garage-Door-Supplier-Garex-Doors-Enr.-300x99.png 300w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/5.-Canadian-Wholesale-Garage-Door-Supplier-Garex-Doors-Enr..png 389w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Fonte: portesgarex.com<\/p>\n<p>Por mais de 30 anos, a Garex se destacou por sua filosofia de gest\u00e3o que coloca os funcion\u00e1rios em primeiro lugar. Nossa equipe est\u00e1 comprometida em oferecer um produto de qualidade. Cada porta \u00e9 fabricada com foco nos detalhes e na satisfa\u00e7\u00e3o total do cliente.<\/p>\n<p>A Garex fabrica portas de garagem cujo design avan\u00e7ado fornece uma efici\u00eancia energ\u00e9tica \u00f3tima. A experiente equipe da Garex presta muita aten\u00e7\u00e3o \u00e0s necessidades e tend\u00eancias do mercado.<\/p>\n<p>Vantagens:<\/p>\n<ul>\n<li>Ampla sele\u00e7\u00e3o de cores e tamanhos<\/li>\n<li>Projetado para ser energeticamente eficiente<\/li>\n<li>Fabricado para atender ao clima atual<\/li>\n<li>Ofere\u00e7a uma porta com funcionamento suave<\/li>\n<li>Atendimento personalizado ao cliente<\/li>\n<li>Uma vasta rede de distribuidores para atend\u00ea-lo<\/li>\n<\/ul>\n<p>Sede: 610, rue Principale, Val-Alain (Quebec) G0S 3H0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-4679\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-4679 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d334070128-61010222\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d334070128-61010222\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d334070128-61010222\" data-class=\"content-6a57d334070128-61010222\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-5620\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-5620 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o5\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o5\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o5\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o5\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Portas de garagem Barmac<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter wp-image-4542\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/6.-Canadian-Wholesale-Garage-Door-Supplier-Barmac-Garage-Doors.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - Barmac Garage Doors\" width=\"300\" height=\"121\" \/>Fonte: barmacdoors.com<\/p>\n<p>A Barmac Garage Doors tem orgulho de oferecer uma grande variedade de portas de garagem residenciais de \u00faltima gera\u00e7\u00e3o que proporcionam a apar\u00eancia e a conveni\u00eancia que os clientes desejam para sua casa.<\/p>\n<p>Usando v\u00e1rios produtos e materiais, a sele\u00e7\u00e3o de portas de garagem da Barmac varia de portas de madeira personalizadas de alta qualidade a portas de a\u00e7o de baixa manuten\u00e7\u00e3o e portas de madeira projetadas econ\u00f4micas e dur\u00e1veis. N\u00f3s carregamos portas de garagem residenciais de a\u00e7o fabricadas pelo l\u00edder da ind\u00fastria Garaga Garage Doors\u00ae.<\/p>\n<p>Principais produtos:<\/p>\n<ul>\n<li>Port\u00f5es de garagem residenciais<\/li>\n<li>Port\u00f5es de garagem contempor\u00e2neos<\/li>\n<li>Portas de garagem estilo carruagem<\/li>\n<li>Portas de garagem tradicionais<\/li>\n<li>Port\u00f5es de garagem comerciais<\/li>\n<\/ul>\n<p>Sede: 60 Talman Ct, Concord, ON L4K 4L5<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-3492\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-3492 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d33408ce17-81753103\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d33408ce17-81753103\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d33408ce17-81753103\" data-class=\"content-6a57d33408ce17-81753103\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-4124\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-4124 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o6\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o6\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o6\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o6\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>O dep\u00f3sito da porta da garagem<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-medium wp-image-4543 aligncenter\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/7.-Canadian-Wholesale-Garage-Door-Supplier-The-Garage-Door-Depot-300x78.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - The Garage Door Depot\" width=\"300\" height=\"78\" srcset=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/7.-Canadian-Wholesale-Garage-Door-Supplier-The-Garage-Door-Depot-300x78.png 300w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/7.-Canadian-Wholesale-Garage-Door-Supplier-The-Garage-Door-Depot-1024x267.png 1024w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/7.-Canadian-Wholesale-Garage-Door-Supplier-The-Garage-Door-Depot-768x201.png 768w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/7.-Canadian-Wholesale-Garage-Door-Supplier-The-Garage-Door-Depot.png 1436w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Fonte: garagedoordepot.ca<\/p>\n<p>A Garage Door Depot da Grande Vancouver \u00e9 uma empresa de portas basculantes comerciais\/residenciais em opera\u00e7\u00e3o que oferece suporte a clientes comerciais e residenciais e suas necessidades. A GDD Vancouver tem orgulhosamente atendido a \u00e1rea da Grande Vancouver desde 2005. Al\u00e9m de atender seu mercado local, a GDD Vancouver tamb\u00e9m fornece treinamento e suporte a outras unidades da Garage Door Depot em todo o pa\u00eds.<\/p>\n<p>O GDD License Group \u00e9 uma empresa totalmente separada que se concentra exclusivamente em dar suporte e desenvolver a marca Garage Door Depot na Am\u00e9rica do Norte. Tamb\u00e9m com sede na \u00e1rea da Grande Vancouver, o GDD License Group gerencia os v\u00e1rios acordos de franquia e licen\u00e7a de marca em vigor, bem como trabalha para expandir a marca GDD para novos mercados.<\/p>\n<p>Principais produtos:<\/p>\n<ul>\n<li>Portas Residenciais<\/li>\n<li>Portas Comerciais<\/li>\n<li>Abridores de portas de garagem<\/li>\n<\/ul>\n<p>Sede: 120-19055 Airport WayPitt Meadows, BCV3Y 0G4<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-8464\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-8464 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d3340a9e57-88876813\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d3340a9e57-88876813\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d3340a9e57-88876813\" data-class=\"content-6a57d3340a9e57-88876813\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-6625\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-6625 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o7\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o7\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o7\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o7\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Portas inteligentes<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter wp-image-4544\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/8.-Canadian-Wholesale-Garage-Door-Supplier-Smart-Doors.jpg\" alt=\"Fornecedor canadense de portas de garagem por atacado - Smart Doors\" width=\"300\" height=\"186\" \/>Fonte: smartdoors.ca<\/p>\n<p>A Smart Doors oferece servi\u00e7os e instala\u00e7\u00f5es de qualidade, juntamente com uma sele\u00e7\u00e3o variada de portas de garagem residenciais e comerciais em estoque dos principais fabricantes. N\u00f3s apoiamos nossos fabricantes com nossa garantia de m\u00e3o de obra sem complica\u00e7\u00f5es de dois anos. Nossos fabricantes tamb\u00e9m oferecem suas pr\u00f3prias garantias de pe\u00e7as que cobrem muitos de seus produtos por toda a vida. A garantia da Smart Doors est\u00e1 entre as melhores do setor.<\/p>\n<p>Na Smart Doors, garantimos a qualidade dos nossos produtos e o servi\u00e7o confi\u00e1vel, proporcionando aos nossos clientes uma experi\u00eancia agrad\u00e1vel e inesquec\u00edvel.<\/p>\n<p>Principais produtos:<\/p>\n<ul>\n<li>Portas de garagem de vidro<\/li>\n<li>Portas de garagem modernas<\/li>\n<li>Portas de garagem personalizadas<\/li>\n<\/ul>\n<p>Sede: 40 Viceroy Rd. Unidade 8, Concord, ON, L4K2L8<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-2241\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-2241 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d3340c7439-74293233\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d3340c7439-74293233\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d3340c7439-74293233\" data-class=\"content-6a57d3340c7439-74293233\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-6255\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-6255 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o8\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o8\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o8\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o8\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Produtos para portas de a\u00e7o artesanais Ltda.<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full wp-image-4545 aligncenter\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/9.-Canadian-Wholesale-Garage-Door-Supplier-Steel-Craft-Door-Products-Ltd..png\" alt=\"Fornecedor canadense de portas de garagem por atacado - Steel Craft Door Products Ltd.\" width=\"300\" height=\"139\" \/>Fonte: steel-craft.ca<\/p>\n<p>A Steel-Craft Door Products Ltd. fabrica portas residenciais, comerciais e industriais desde 1963. Nossa unidade de fabrica\u00e7\u00e3o de 325.000 p\u00e9s quadrados est\u00e1 localizada em Edmonton, Alberta, Canad\u00e1. Al\u00e9m do centro de distribui\u00e7\u00e3o adjacente, temos v\u00e1rios outros locais de distribui\u00e7\u00e3o em todo o Canad\u00e1 para nos ajudar a atender \u00e0 forte demanda por nossos produtos.<\/p>\n<p>Todos os produtos Steel-Craft s\u00e3o constru\u00eddos de acordo com os mais altos padr\u00f5es de engenharia, e nossa instala\u00e7\u00e3o interna testa nossos produtos em rela\u00e7\u00e3o aos rigorosos padr\u00f5es da ind\u00fastria e muito mais. Oferecemos nossos produtos de portas orgulhosamente superprojetados por meio de revendedores e distribuidores autorizados da Steel-Craft.<\/p>\n<p>Sede: 13504 St Albert Trail, Edmonton, AB T5L 4P4, Canad\u00e1<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-7057\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-7057 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d3340e5022-05962630\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d3340e5022-05962630\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d3340e5022-05962630\" data-class=\"content-6a57d3340e5022-05962630\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-566\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-566 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o9\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o9\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o9\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o9\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Portas de garagem Easy Flip<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-medium wp-image-4546 aligncenter\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/10.-Canadian-Wholesale-Garage-Door-Supplier-Easy-Flip-Garage-Doors-300x156.png\" alt=\"Fornecedor canadense de portas de garagem por atacado - Portas de garagem Easy Flip\" width=\"300\" height=\"156\" srcset=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/10.-Canadian-Wholesale-Garage-Door-Supplier-Easy-Flip-Garage-Doors-300x156.png 300w, https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/10.-Canadian-Wholesale-Garage-Door-Supplier-Easy-Flip-Garage-Doors.png 311w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Fonte: easyflipgaragedoors.ca<\/p>\n<p>A Easy Flip Garage Doors \u00e9 especializada na instala\u00e7\u00e3o, reparos e manuten\u00e7\u00e3o de portas de garagem residenciais suspensas, abridores de portas de garagem e tampas de alum\u00ednio.<\/p>\n<p>Oferecemos uma ampla variedade de estilos e cores para atender \u00e0s suas necessidades de porta de garagem. Fornecemos tr\u00eas marcas diferentes: Amarr, CHI e Garaga. Escolhemos apenas a melhor qualidade para nossos clientes e tamb\u00e9m uma que seja adequada para o clima canadense<\/p>\n<p>Sede: Unidade 5- 3 Watson Road South, Guelph, ON N1L 1E3<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-1530\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-1530 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d334102536-34129482\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d334102536-34129482\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d334102536-34129482\" data-class=\"content-6a57d334102536-34129482\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-6233\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-6233 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o10\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o10\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o10\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o10\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Um fabricante alternativo de portas de garagem<\/h2>\n<p>Escolher o melhor fabricante e fornecedor de garagem \u00e9 muito importante, sem procurar mais, somos um dos l\u00edderes <a href=\"https:\/\/www.raxdoor.com\/pt\/garage-door\/\" target=\"_blank\" rel=\"noopener\">empresas de portas de garagem<\/a> na China com mais de 20 anos de experi\u00eancia, e podemos oferecer a voc\u00ea um servi\u00e7o que \u00e9 inigual\u00e1vel. A Raxdoor n\u00e3o vai te decepcionar.<\/p>\n<p>Se voc\u00ea est\u00e1 procurando portas de garagem de alta qualidade a um pre\u00e7o competitivo na China, entre em contato conosco no bot\u00e3o abaixo.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"modal-trg-txt-wrap-3994\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin   vc_custom_1630846613086\" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-3994 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#f39402;border-color:#f39402;color:#ffffff; \" data-class-id=\"content-6a57d33411f244-19028696\" class=\"btn-modal ult-responsive btn-primary btn-modal-md overlay-show ult-align-center btn-id-6a57d33411f244-19028696\" data-overlay-class=\"overlay-cornerbottomleft\">Obter or\u00e7amento gr\u00e1tis<\/button><\/div>\n<div class=\"ult-overlay content-6a57d33411f244-19028696\" data-class=\"content-6a57d33411f244-19028696\" id=\"button-click-overlay\" style=\"background:rgba(51,51,51,0); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-small\">\n\t<div class=\"ult-overlay-close popup-edge-top-right\" style=\"width:20px;height:20px; background-color: #2e72ab;border-radius: 50%;padding:10px;box-sizing: content-box; top:-20px;right:-20px;\"><div class=\"ult-overlay-close-inside\">Fechar<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-529\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#000000;\">\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-529 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9-o11\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o11\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/posts\/3001#wpcf7-f9-o11\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9-o11\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-383\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu nome*\" value=\"\" type=\"text\" name=\"text-383\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-983\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu e-mail*\" value=\"\" type=\"email\" name=\"email-983\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-963\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sua mensagem*\" name=\"textarea-963\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua solicita\u00e7\u00e3o\" \/><br \/>\n<span style=\"font-size: 9pt;\"><span style=\"color: #999999;\">Este site \u00e9 protegido pelo reCAPTCHA e pelo Google <\/span><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #66b3f2;\">pol\u00edtica de Privacidade<\/span><\/a> <span style=\"color: #999999;\">e<\/span> <span style=\"color: #66b3f2;\"><a style=\"color: #66b3f2;\" href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termos de servi\u00e7o<\/a><\/span>\u00a0<span style=\"color: #999999;\">aplicar<\/span>.<\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/www.raxdoor.com\/wp-content\/uploads\/2021\/12\/Wholesale-Garage-Door-Suppliers-in-Canada.jpg\" width=\"700\" height=\"425\" alt=\"Fornecedores de portas de garagem por atacado no Canad\u00e1\" title=\"Fornecedores de portas de garagem por atacado no Canad\u00e1\"  data-dt-location=\"https:\/\/www.raxdoor.com\/pt\/garage-door-suppliers-in-canada\/wholesale-garage-door-suppliers-in-canada\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><span id=\"More_Information_about_Garage_door_Opener\">Mais informa\u00e7\u00f5es sobre portas de garagem:<\/span><\/h3>\n<ul>\n<li class=\"entry-title\">\n<p class=\"entry-title\"><a href=\"https:\/\/www.raxdoor.com\/pt\/types-of-garage-doors\/\">Tipos de portas de garagem \u2013 Quanto custam?<\/a><\/p>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;3001&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;136&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.9\\\/5 - (136 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Top 10 Garage Door Suppliers \\u0026amp; Wholesalers in Canada&quot;,&quot;width&quot;:&quot;135.2&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 135.2px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            4.9\/5 - (136 votos)    <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea quer saber quem est\u00e1 liderando a ind\u00fastria de portas de garagem no Canad\u00e1? Neste artigo, listamos os principais fornecedores e atacadistas de portas de garagem para aplica\u00e7\u00f5es residenciais, comerciais e industriais. Principais empresas de portas de garagem no Canad\u00e1 A One Garage Doors Fonte: aonegaragedoors.com A A-ONE Garage Door projeta e fabrica portas de garagem isoladas de alta qualidade\u2026<\/p>","protected":false},"author":1,"featured_media":6252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-3001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-34","description-off"],"_links":{"self":[{"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/posts\/3001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/comments?post=3001"}],"version-history":[{"count":0,"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/posts\/3001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/media\/6252"}],"wp:attachment":[{"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/media?parent=3001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/categories?post=3001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.raxdoor.com\/pt\/wp-json\/wp\/v2\/tags?post=3001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}